{"id":66763,"date":"2023-05-12T12:01:49","date_gmt":"2023-05-12T10:01:49","guid":{"rendered":"https:\/\/www.accretech.eu\/?p=66763"},"modified":"2023-07-05T10:22:58","modified_gmt":"2023-07-05T08:22:58","slug":"la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech","status":"publish","type":"post","link":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/","title":{"rendered":"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter &#8220;decolla&#8221; grazie ad ACCRETECH"},"content":{"rendered":"\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-j82psr-038a4098dfa289c076de915ff4eb220b\">\n.flex_column.av-j82psr-038a4098dfa289c076de915ff4eb220b{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-j82psr-038a4098dfa289c076de915ff4eb220b av_one_full first flex_column_div av-zero-column-padding '     ><section  class='av_textblock_section av-juzpi7tc-f08a8ed8ab3ab7f0de716cc0bca94084'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h1 style=\"color: #154194;\">La qualit\u00e0 di Hill Helicopters &#8220;decolla&#8221; grazie ad ACCRETECH<\/h1>\n<p><b style=\"color: #154194; font-family: f45;\">In un settore globale estremamente competitivo come quello aerospaziale &#8211; in cui i produttori devono garantire la precisione delle loro apparecchiature di controllo &#8211; la qualit\u00e0, la velocit\u00e0 e l&#8217;efficienza operativa degli strumenti di misura stanno diventando sempre pi\u00f9 importanti. La recente installazione di una macchina per la misurazione di superfici e profili ACCRETECH SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale quando sono in grado di ottenere risultati di ispezione rapidi e ad alta precisione.<\/b><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-j82psr-11-394f4798640f3cce93c8c2fb99483031\">\n.flex_column.av-j82psr-11-394f4798640f3cce93c8c2fb99483031{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-j82psr-11-394f4798640f3cce93c8c2fb99483031 av_one_full first flex_column_div av-zero-column-padding '     ><section  class='av_textblock_section av-juzpi7tc-10-b384f9a2b1a24d6087feeb862a7ab062'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>Hill Helicopters, azienda inglese con sede nello Staffordshire, \u00e8 stata pioniera di un nuovo approccio nell\u2019offerta di velivoli privati di lusso, sicuri ed emozionanti, a un prezzo accessibile. L&#8217;azienda chiama questo approccio General Aviation 2.0. General Aviation 2.0 (GA2.0) si estende ben oltre il velivolo: rappresenta un&#8217;esperienza di propriet\u00e0 end-to-end che offre ai clienti l&#8217;aeromobile che hanno sempre desiderato coniugandolo con tutta l\u2019assistenza necessaria per ottenere il meglio dall&#8217;aviazione privata.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-31gcb4p-d0f4206a086ac7047cf52ca296b47ea6\">\n.flex_column.av-31gcb4p-d0f4206a086ac7047cf52ca296b47ea6{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-31gcb4p-d0f4206a086ac7047cf52ca296b47ea6 av_one_full first flex_column_div av-zero-column-padding '     ><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='av-layout-grid-1'  class='av-layout-grid-container av-505x97d-a3ecc8a1eb490af85f784d1f613ddcbf entry-content-wrapper main_color av-flex-cells  container_wrap fullsize'  >\n<div class='flex_cell av-4i9ho0p-ee3a9de2fb2cbf2bfa5c0e3e0a5ee1e0 av-gridrow-cell av_one_fourth no_margin' ><div class='flex_cell_inner'><\/div><\/div><div class='flex_cell av-44kglyx-e5888402d285424cebb00a5f308b74e1 av-gridrow-cell av_one_half no_margin' ><div class='flex_cell_inner'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-r4fphm-f5075d81fb0ece926fd9a38e011c2a91\">\n.flex_column.av-r4fphm-f5075d81fb0ece926fd9a38e011c2a91{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 20px 0px;\n}\n<\/style>\n<div class='flex_column av-r4fphm-f5075d81fb0ece926fd9a38e011c2a91 av_one_full first flex_column_div '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l8cq0m9b-5fd598b06417bc47dbd1a62834baad3f\">\n.avia-image-container.av-l8cq0m9b-5fd598b06417bc47dbd1a62834baad3f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l8cq0m9b-5fd598b06417bc47dbd1a62834baad3f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l8cq0m9b-5fd598b06417bc47dbd1a62834baad3f av-styling- avia-align-center'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-66387 avia-img-lazy-loading-not-66387 avia_image ' src=\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-495x400.jpg\" alt='' title='SM-11'  height=\"400\" width=\"495\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-495x400.jpg 495w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-845x684.jpg 845w\" sizes=\"(max-width: 495px) 100vw, 495px\" \/><\/div><\/div><\/div><\/div>\n<\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3i50jcp-2c2e10e80d2af8deb00b74b2f75b382f\">\n.flex_cell.av-3i50jcp-2c2e10e80d2af8deb00b74b2f75b382f{\nvertical-align:top;\n}\n<\/style>\n<div class='flex_cell av-3i50jcp-2c2e10e80d2af8deb00b74b2f75b382f av-gridrow-cell av_one_fourth no_margin' ><div class='flex_cell_inner'><\/div><\/div>\n<\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-r4fphm-7-85ccd9ce5ca6946fbfa97e86cdf81c95\">\n.flex_column.av-r4fphm-7-85ccd9ce5ca6946fbfa97e86cdf81c95{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-r4fphm-7-85ccd9ce5ca6946fbfa97e86cdf81c95 av_one_fifth first flex_column_div av-zero-column-padding '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-j82psr-9-90b06bc0ccef801daac7878106465703\">\n.flex_column.av-j82psr-9-90b06bc0ccef801daac7878106465703{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-j82psr-9-90b06bc0ccef801daac7878106465703 av_one_full first flex_column_div av-zero-column-padding '     ><section  class='av_textblock_section av-juzpi7tc-8-21dd6141a077b42765b3aaee5529cfff'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>Il dottor Jason Hill, fondatore e CEO di Hill Helicopters, ha recentemente presentato l&#8217;HX50, un nuovo concept di elicottero a cinque posti a turbina costruito nel Regno Unito. Al fine di consentire un&#8217;ispezione estremamente efficiente e precisa delle superfici e dei profili di tutti i componenti prodotti internamente, Hill Helicopters ha recentemente acquistato un SURFCOM NEX 240 DX-13 da ACCRETECH UK.<\/p>\n<p>Mark Webb, Lead Production Engineer di Hill Helicopters, spiega le ragioni dietro alla scelta della macchina recentemente installata: <em>&#8221; Hill Helicopter descrive l&#8217;HX50 come un&#8217;esperienza completamente nuova in termini di sicurezza, prestazioni, avventura, comfort ed eleganza. Non \u00e8 una coincidenza che la &#8220;sicurezza&#8221; sia al primo posto in questo elenco di caratteristiche. Per garantire i pi\u00f9 elevati standard di sicurezza, supervisioniamo un rigoroso regime di qualit\u00e0 a livello aziendale. Oltre a disporre di personale qualificato e preparato, investiamo nelle migliori attrezzature di ispezione disponibili.<\/em><\/p>\n<p><em>&#8220;L&#8217;ultima arrivata nella nostra impressionante lista di dispositivi di controllo \u00e8 l&#8217;avanzata SURFCOM NEX 240 DX-13. Cercavamo uno strumento di misura di superfici e profili ad alta precisione e ad azione rapida: alla fine abbiamo concluso che questa avanzata macchina ACCRETECH fosse quella che soddisfaceva al meglio i nostri esigenti standard di precisione ed efficienza. Oltre alle prestazioni dello strumento, nella nostra decisione ha avuto un peso determinante la reputazione di ACCRETECH per la produzione di macchine di alta qualit\u00e0 e per l&#8217;eccellente servizio di assistenza ai clienti.<\/em><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-17nnc5p-884c8bb425632bb3f33e6e143b90370e\">\n.flex_column.av-17nnc5p-884c8bb425632bb3f33e6e143b90370e{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-17nnc5p-884c8bb425632bb3f33e6e143b90370e av_one_full first flex_column_div av-zero-column-padding '     ><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-j82psr-4-7d005c5bea3179e0de156abf0729b245\">\n.flex_column.av-j82psr-4-7d005c5bea3179e0de156abf0729b245{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-j82psr-4-7d005c5bea3179e0de156abf0729b245 av_two_third first flex_column_div av-zero-column-padding '     ><section  class='av_textblock_section av-juzpi7tc-3-9c97ed436119a8c35229e5bc96327b31'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><h2>Garantire qualit\u00e0 e flessibilit\u00e0 mentre crescono i volumi<\/h2>\n<p>P.E.L Pintossi si \u00e8 evoluta negli anni per potersi adattare alle nuove richieste ed esigenze del mercato, con la richiesta di componenti sempre pi\u00f9 complessi e uno spostamento della clientela dal mercato domestico a quello internazionale. Spiega Balduchelli: \u201c<em>Il nostro vantaggio competitivo \u00e8 sicuramente la flessibilit\u00e0 che ci permette di produrre in maniera efficienza componenti di tipo diverso e in diverse dimensioni di commessa: lavoriamo con lotti da 50 pezzi fino a pi\u00f9 di 100.000<\/em>.\u201d La produzione \u00e8 affidata oggi prevalentemente a moderne macchine transfer a controllo numerico, che progressivamente hanno affiancato e quindi sostituito macchinari tradizionali, che continuano ad essere utilizzati per lavorazioni pi\u00f9 semplici<em>. <\/em>La crescita dell\u2019azienda \u00e8 visibile: negli ultimi anni la metratura dello stabilimento principale \u00e8 aumentata fino a quasi raddoppiare, e ospita oggi 35 macchine a trasferimento automatico, ciascuna in grado di effettuare diverse lavorazioni sullo stesso pezzo, e questo porta ad una moltiplicazione della complessit\u00e0 e delle esigenze di controllo, come spiega Balduchelli: \u201c<em>Il nostro reparto collaudo \u00e8 oggi composto da sette addetti che svolgono cicli orari di controllo su ciascuna macchina, con diversi test in base il ciclo di controllo previsto per quella lavorazione.\u201d. <\/em>Oltre al controllo su base oraria, viene inoltre effettuato un controllo iniziale per ottenere il benestare all\u2019inizio della produzione di ogni commessa, su ogni singola macchina coinvolta.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-r4fphm-5-c580ee1d8c420afbb3ecf0086bfe58a5\">\n.flex_column.av-r4fphm-5-c580ee1d8c420afbb3ecf0086bfe58a5{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 20px 0px;\n}\n<\/style>\n<div class='flex_column av-r4fphm-5-c580ee1d8c420afbb3ecf0086bfe58a5 av_one_third flex_column_div '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k9crrdvf-6-135c6bdb96d56b938efafa99b946e65b\">\n.avia-image-container.av-k9crrdvf-6-135c6bdb96d56b938efafa99b946e65b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k9crrdvf-6-135c6bdb96d56b938efafa99b946e65b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k9crrdvf-6-135c6bdb96d56b938efafa99b946e65b av-styling- avia-align-center'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-66398 avia-img-lazy-loading-not-66398 avia_image ' src=\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-200x300.jpg\" alt='' title='SM-12'  height=\"300\" width=\"200\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-200x300.jpg 200w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-687x1030.jpg 687w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-768x1152.jpg 768w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-1024x1536.jpg 1024w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-1365x2048.jpg 1365w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-1000x1500.jpg 1000w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-470x705.jpg 470w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-12-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/div><\/div><\/div><\/div>\n<div class='flex_column av-29k6m8p-6d04c195ce308e1aef57b66298b5e8ab av_one_full first flex_column_div '     ><section  class='av_textblock_section av-l8cq6nqg-1fe6c978a02600aa891e909b466e290d'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>Sulla scia del successo mondiale del precedente prodotto SURFCOM, la gamma ACCRETECH SURFCOM NEX, lanciata di recente, sta attualmente superando tutte le previsioni di vendita. Invece di investire in due costose macchine dedicate, i modelli all&#8217;avanguardia SURFCOM NEX consentono agli utenti di ottenere misure di rugosit\u00e0 e di profilo di alta precisione utilizzando un unico strumento, dal costo contenuto. Oltre a occupare molto meno spazio rispetto a due macchine separate, la nuova gamma altamente efficiente consente inoltre processi di misura fino al 60% pi\u00f9 rapidi.<\/p>\n<p>Data la crescente tendenza a effettuare l&#8217;ispezione dei componenti vicino al punto di produzione, oltre ad essere ideale per l&#8217;uso in camere bianche a temperatura controllata, la robusta gamma SURFCOM NEX pu\u00f2 essere utilizzata anche in ambienti di produzione in serie, grazie alla capacit\u00e0 di fornire risultati accurati a diverse temperature.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2dccgah-aec7bb4196a793ace9c24daa8af31ce5\">\n.flex_column.av-2dccgah-aec7bb4196a793ace9c24daa8af31ce5{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-2dccgah-aec7bb4196a793ace9c24daa8af31ce5 av_one_full first flex_column_div av-zero-column-padding '     ><section  class='av_textblock_section av-l0862h79-be359841403d8e29bf0aa584260311e4'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>Le innovazioni della nuova serie includono l&#8217;uso di un rilevatore ibrido flessibile che consente di effettuare misure combinate di profilo e rugosit\u00e0. Invece di utilizzare un tradizionale gruppo meccanico vite-sfera, le macchine SURFCOM NEX impiegano un sistema di azionamento lineare progressivo che assicura misure rapide e a bassa oscillazione, senza \u201crumori\u201d e vibrazioni di disturbo.<\/p>\n<p>Gran parte del successo della nuova gamma si basa sulla struttura modulare e flessibile delle macchine. Invece di accontentarsi di uno strumento di misura di superfici e contorni che si avvicina alle loro esigenze, i potenziali clienti sono ora in grado di comporre un sistema che soddisfi esattamente le loro necessit\u00e0 specifiche. Ad esempio, la macchina SURFCOM NEX 240 DX-13 di Hill Helicopters \u00e8 dotata di due rilevatori separati: Oltre a un rilevatore ibrido avanzato che consente di effettuare misure simultanee di profilo e rugosit\u00e0 ad alta precisione in un unico passaggio (NEX 200), la variante scelta vanta anche un rilevatore di contorno ad alta risoluzione (NEX 040) che garantisce la possibilit\u00e0 di misura verso l&#8217;alto e verso il basso.<\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-s0hf1p-9835f6531a181a53ca6ddfbdd44e36a2\">\n.flex_column.av-s0hf1p-9835f6531a181a53ca6ddfbdd44e36a2{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-s0hf1p-9835f6531a181a53ca6ddfbdd44e36a2 av_two_third first flex_column_div av-zero-column-padding '     ><section  class='av_textblock_section av-ldoj0lcl-3fd2f89a4e41f898f1c755adcf308c22'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>Tim Wood, ACCRETECH Regional Director North Europe di ACCRETECH ha poi concluso: <em>&#8220;I prodotti ACCRETECH rendono possibile la misurazione ad alta precisione, tattile o senza contatto, della rugosit\u00e0 superficiale e dei profili dei componenti. Le caratteristiche che possono essere ispezionate includono la misurazione di complesse geometrie di profilo in polarizzazione verso l&#8217;alto e verso il basso, e parametri di rugosit\u00e0 e ondulazione della superficie con riferimento a standard globali come ISO, DIN, JIS e ASME. <\/em><\/p>\n<p><em>&#8220;Grazie alla loro struttura modulare, le nostre avanzate apparecchiature di controllo possono essere adattate per soddisfare le esigenze specifiche dei singoli clienti. Poich\u00e9 Hill Helicopters aveva diversi fornitori alternativi tra cui scegliere, siamo stati lieti di ricevere un ordine per una macchina SURFCOM NEX 240 DX-13 di grande capacit\u00e0. Questa versione dispone di una base in granito di 700 mm x 450 mm e di una colonna con una corsa di 450 mm. Per aumentare ulteriormente la precisione, il modello 240 DX-13 di Hill Helicopters \u00e8 stato corredato di un tavolo antivibrazione integrato&#8221;.<\/em><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1rfte5y-9ae4a976f856d9f43b2394cb95b03212\">\n.flex_column.av-1rfte5y-9ae4a976f856d9f43b2394cb95b03212{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 10px 0px;\n}\n<\/style>\n<div class='flex_column av-1rfte5y-9ae4a976f856d9f43b2394cb95b03212 av_one_third flex_column_div '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-ljpg2vh9-1e10d44d40be7d7c7f1c1fbf16e12dee\">\n.avia-image-container.av-ljpg2vh9-1e10d44d40be7d7c7f1c1fbf16e12dee img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-ljpg2vh9-1e10d44d40be7d7c7f1c1fbf16e12dee .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-ljpg2vh9-1e10d44d40be7d7c7f1c1fbf16e12dee av-styling- avia-align-center'   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" class='wp-image-66407 avia-img-lazy-loading-not-66407 avia_image ' src=\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-200x300.jpg\" alt='' title='SM-10'  height=\"300\" width=\"200\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-200x300.jpg 200w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-687x1030.jpg 687w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-768x1152.jpg 768w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-1024x1536.jpg 1024w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-1365x2048.jpg 1365w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-1000x1500.jpg 1000w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-470x705.jpg 470w, https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-10-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/div><\/div><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1b3nydn-0da7868acce07f67a4dca74ee4adf6fd\">\n.flex_column.av-1b3nydn-0da7868acce07f67a4dca74ee4adf6fd{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 10px 0px;\n}\n<\/style>\n<div class='flex_column av-1b3nydn-0da7868acce07f67a4dca74ee4adf6fd av_one_third first flex_column_div '     ><section  class='av_textblock_section av-mpjq97-e740a0e98fd495ec1354a7e910299dea'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p><b style=\"color: #154194; font-family: f45;\">Kontakt:<\/b><\/p>\n<p>ACCRETECH (Europe) GmbH<br \/>\nRoberto Rancati<br \/>\nRegional Account Manager<br \/>\nVia Giotto. 7<br \/>\n20032 Cormano (MI),<br \/>\nItaly<br \/>\nPhone: +39 02 2316 3291<br \/>\n<a href=\"mailto:horstj@accretech.eu\">RancatiR@accretech.eu<\/a><\/p>\n<\/div><\/section><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-nl79vs-79102560532c51159c2b725e0e2f6a27\">\n.flex_column.av-nl79vs-79102560532c51159c2b725e0e2f6a27{\n-webkit-border-radius:0px 0px 0px 0px;\n-moz-border-radius:0px 0px 0px 0px;\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div class='flex_column av-nl79vs-79102560532c51159c2b725e0e2f6a27 av_three_fourth first no_margin flex_column_div av-zero-column-padding '     ><p><section  class='av_textblock_section av-jwvueht8-2-1d5bb8029d6977a5905bdd235cb90d18'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p><span style=\"font-family: f45; color: #154194;\"><strong><i class=\"wp-svg-arrow-right-2 arrow-right-2\"><\/i><a href=\"https:\/\/www.accretech.eu\/it\/surfcom-nex-040041\/\"> SURFCOM NEX<\/a><\/strong><\/span><\/p>\n<\/div><\/section><br \/>\n<section  class='av_textblock_section av-jwvueht8-1-28b60c7e323759cbcd42d4cbb02b83fa'  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p><span style=\"font-family: f45; color: #154194;\"><strong><i class=\"wp-svg-arrow-right-2 arrow-right-2\"><\/i><a href=\"https:\/\/www.accretech.eu\/en\/about-accretech\/accretech-news\/\"> News<\/a><\/strong><\/span><\/p>\n<\/div><\/section><\/p><\/div>\n<div class='flex_column av-1piy40p-419395df03cf13590ed2b97a567f6521 av_three_fifth first flex_column_div '     ><\/div>\n<div class='flex_column av-1b6ipw9-003f89f1c022d32474bb8369a0437f4f av_three_fifth first flex_column_div '     ><div  class='avia-video av-ldojqfhl-28f09fd67f17ffc903fb8cf72e4b61b0 avia-video-16-9 av-no-preview-image avia-video-load-always av-lazyload-immediate av-lazyload-video-embed'  itemprop=\"video\" itemtype=\"https:\/\/schema.org\/VideoObject\"  data-original_url='https:\/\/www.youtube.com\/watch?v=0iWwb19csE0&amp;t=31s'><script type='text\/html' class='av-video-tmpl'> <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"youtube-content-blocker\" data-borlabs-cookie-content=\"PGRpdiBjbGFzcz0nYXZpYS1pZnJhbWUtd3JhcCc+PGlmcmFtZSB0aXRsZT0iU1VSRkNPTSBORVggU2VyaWVzIiB3aWR0aD0iMTUwMCIgaGVpZ2h0PSI4NDQiIHNyYz0iaHR0cHM6Ly93d3cueW91dHViZS1ub2Nvb2tpZS5jb20vZW1iZWQvMGlXd2IxOWNzRTA\/c3RhcnQ9MzEmZmVhdHVyZT1vZW1iZWQiIGZyYW1lYm9yZGVyPSIwIiBhbGxvdz0iYWNjZWxlcm9tZXRlcjsgYXV0b3BsYXk7IGNsaXBib2FyZC13cml0ZTsgZW5jcnlwdGVkLW1lZGlhOyBneXJvc2NvcGU7IHBpY3R1cmUtaW4tcGljdHVyZTsgd2ViLXNoYXJlIiBhbGxvd2Z1bGxzY3JlZW4+PC9pZnJhbWU+PC9kaXY+\"><div class=\"brlbs-cmpnt-cb-preset-c brlbs-cmpnt-cb-youtube\"> <div class=\"brlbs-cmpnt-cb-thumbnail\" style=\"background-image: url('https:\/\/www.accretech.eu\/wp-content\/uploads\/borlabs-cookie\/1\/yt_0iWwb19csE0_hqdefault.jpg')\"><\/div> <div class=\"brlbs-cmpnt-cb-main\"> <div class=\"brlbs-cmpnt-cb-play-button\"><\/div> <div class=\"brlbs-cmpnt-cb-content\"> <p class=\"brlbs-cmpnt-cb-description\">Stai visualizzando un contenuto segnaposto da <strong>Youtube<\/strong>. Per accedere al contenuto effettivo, clicca sul pulsante sottostante. Si prega di notare che in questo modo si condividono i dati con provider di terze parti.<\/p> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">Ulteriori informazioni<\/a> <\/div> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Sblocca i contenuti<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: inherit\">Accetta il servizio richiesto e sblocca i contenuti<\/a> <\/div> <\/div> <\/div><\/div><\/script><div class='av-click-to-play-overlay'><div class=\"avia_playpause_icon\"><\/div><\/div><\/div><\/div>\n<div class='flex_column av-vvi4st-82caf79e8b46ea10c29cb22a380e4376 av_one_half first flex_column_div '     ><\/div>\n<div class='flex_column av-2l180p-4c34f19e54e13449c2a75c70d43225a9 av_one_full first flex_column_div '     ><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In un settore globale estremamente competitivo come quello aerospaziale &#8211; in cui i produttori devono garantire la precisione delle loro apparecchiature di controllo &#8211; la qualit\u00e0, la velocit\u00e0 e l&#8217;efficienza operativa degli strumenti di misura stanno diventando sempre pi\u00f9 importanti. La recente installazione di una macchina per la misurazione di superfici e profili ACCRETECH SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale quando sono in grado di ottenere risultati di ispezione rapidi e ad alta precisione. <\/p>\n","protected":false},"author":550,"featured_media":66387,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[55],"tags":[],"class_list":["post-66763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-categorizzato"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.1 (Yoast SEO v26.1.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La qualit\u00e0 di Hill Helicopter &quot;decolla&quot; grazie ad ACCRETECH<\/title>\n<meta name=\"description\" content=\"La recente installazione di una macchina per la misurazione di superfici e profili SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter &quot;decolla&quot; grazie ad ACCRETECH\" \/>\n<meta property=\"og:description\" content=\"La recente installazione di una macchina per la misurazione di superfici e profili SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\" \/>\n<meta property=\"og:site_name\" content=\"ACCRETECH (Europe)\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-12T10:01:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T08:22:58+00:00\" \/>\n<meta name=\"author\" content=\"Prause\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Prause\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\"},\"author\":{\"name\":\"Prause\",\"@id\":\"https:\/\/www.accretech.eu\/it\/#\/schema\/person\/fe8e7c1b6514a093af2bc69863486cd6\"},\"headline\":\"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter &#8220;decolla&#8221; grazie ad ACCRETECH\",\"datePublished\":\"2023-05-12T10:01:49+00:00\",\"dateModified\":\"2023-07-05T08:22:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\"},\"wordCount\":4673,\"publisher\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg\",\"articleSection\":[\"Non categorizzato\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\",\"url\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\",\"name\":\"La qualit\u00e0 di Hill Helicopter \\\"decolla\\\" grazie ad ACCRETECH\",\"isPartOf\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg\",\"datePublished\":\"2023-05-12T10:01:49+00:00\",\"dateModified\":\"2023-07-05T08:22:58+00:00\",\"description\":\"La recente installazione di una macchina per la misurazione di superfici e profili SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage\",\"url\":\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg\",\"contentUrl\":\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.accretech.eu\/it\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter &#8220;decolla&#8221; grazie ad ACCRETECH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.accretech.eu\/it\/#website\",\"url\":\"https:\/\/www.accretech.eu\/it\/\",\"name\":\"ACCRETECH (Europe)\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.accretech.eu\/it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.accretech.eu\/it\/#organization\",\"name\":\"ACCRETECH (Europe) GmbH\",\"url\":\"https:\/\/www.accretech.eu\/it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.accretech.eu\/it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2016\/10\/accretech-europe_logo.png\",\"contentUrl\":\"https:\/\/www.accretech.eu\/wp-content\/uploads\/2016\/10\/accretech-europe_logo.png\",\"width\":312,\"height\":42,\"caption\":\"ACCRETECH (Europe) GmbH\"},\"image\":{\"@id\":\"https:\/\/www.accretech.eu\/it\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.accretech.eu\/it\/#\/schema\/person\/fe8e7c1b6514a093af2bc69863486cd6\",\"name\":\"Prause\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La qualit\u00e0 di Hill Helicopter \"decolla\" grazie ad ACCRETECH","description":"La recente installazione di una macchina per la misurazione di superfici e profili SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/","og_locale":"it_IT","og_type":"article","og_title":"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter \"decolla\" grazie ad ACCRETECH","og_description":"La recente installazione di una macchina per la misurazione di superfici e profili SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale.","og_url":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/","og_site_name":"ACCRETECH (Europe)","article_published_time":"2023-05-12T10:01:49+00:00","article_modified_time":"2023-07-05T08:22:58+00:00","author":"Prause","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Prause","Tempo di lettura stimato":"12 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#article","isPartOf":{"@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/"},"author":{"name":"Prause","@id":"https:\/\/www.accretech.eu\/it\/#\/schema\/person\/fe8e7c1b6514a093af2bc69863486cd6"},"headline":"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter &#8220;decolla&#8221; grazie ad ACCRETECH","datePublished":"2023-05-12T10:01:49+00:00","dateModified":"2023-07-05T08:22:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/"},"wordCount":4673,"publisher":{"@id":"https:\/\/www.accretech.eu\/it\/#organization"},"image":{"@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg","articleSection":["Non categorizzato"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/","url":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/","name":"La qualit\u00e0 di Hill Helicopter \"decolla\" grazie ad ACCRETECH","isPartOf":{"@id":"https:\/\/www.accretech.eu\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage"},"image":{"@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage"},"thumbnailUrl":"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg","datePublished":"2023-05-12T10:01:49+00:00","dateModified":"2023-07-05T08:22:58+00:00","description":"La recente installazione di una macchina per la misurazione di superfici e profili SURFCOM NEX presso la sede di Hill Helicopters dimostra i vantaggi per le aziende nel settore aerospaziale.","breadcrumb":{"@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#primaryimage","url":"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg","contentUrl":"https:\/\/www.accretech.eu\/wp-content\/uploads\/2023\/05\/SM-11-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.accretech.eu\/it\/la-qualita-di-hill-helicopter-decolla-grazie-ad-accretech\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.accretech.eu\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Rapporto di progetto: La qualit\u00e0 di Hill Helicopter &#8220;decolla&#8221; grazie ad ACCRETECH"}]},{"@type":"WebSite","@id":"https:\/\/www.accretech.eu\/it\/#website","url":"https:\/\/www.accretech.eu\/it\/","name":"ACCRETECH (Europe)","description":"","publisher":{"@id":"https:\/\/www.accretech.eu\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.accretech.eu\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.accretech.eu\/it\/#organization","name":"ACCRETECH (Europe) GmbH","url":"https:\/\/www.accretech.eu\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.accretech.eu\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.accretech.eu\/wp-content\/uploads\/2016\/10\/accretech-europe_logo.png","contentUrl":"https:\/\/www.accretech.eu\/wp-content\/uploads\/2016\/10\/accretech-europe_logo.png","width":312,"height":42,"caption":"ACCRETECH (Europe) GmbH"},"image":{"@id":"https:\/\/www.accretech.eu\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.accretech.eu\/it\/#\/schema\/person\/fe8e7c1b6514a093af2bc69863486cd6","name":"Prause"}]}},"_links":{"self":[{"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/posts\/66763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/users\/550"}],"replies":[{"embeddable":true,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/comments?post=66763"}],"version-history":[{"count":3,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/posts\/66763\/revisions"}],"predecessor-version":[{"id":66768,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/posts\/66763\/revisions\/66768"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/media\/66387"}],"wp:attachment":[{"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/media?parent=66763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/categories?post=66763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.accretech.eu\/it\/wp-json\/wp\/v2\/tags?post=66763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}